{"id":2987,"date":"2023-05-19T15:01:19","date_gmt":"2023-05-19T15:01:19","guid":{"rendered":"https:\/\/qwery.ancorathemes.com\/?post_type=cpt_portfolio&#038;p=2987"},"modified":"2023-05-30T16:24:18","modified_gmt":"2023-05-30T16:24:18","slug":"personal-driver","status":"publish","type":"cpt_portfolio","link":"https:\/\/thecarltonhotelfolkestone.com\/2026\/portfolio\/personal-driver\/","title":{"rendered":"Personal driver"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Lorem ipsum dolor<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Dicta sunt explicabo. Nemo enim ipsam voluptatem quia voluptas sit aspernatur aut odit aut fugit, quia. Dicta sunt explicabo. Adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim minim veniam quis nostrud exercitation ipsam voluptatem.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"799\" data-id=\"33039\" src=\"https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-1-1024x799.jpg\" alt=\"\" class=\"wp-image-33039\" srcset=\"https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-1-1024x799.jpg 1024w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-1-300x234.jpg 300w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-1-768x600.jpg 768w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-1-1536x1199.jpg 1536w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-1-370x289.jpg 370w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-1-840x656.jpg 840w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-1-410x320.jpg 410w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-1-600x468.jpg 600w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-1.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"799\" data-id=\"33040\" src=\"https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-2-1024x799.jpg\" alt=\"\" class=\"wp-image-33040\" srcset=\"https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-2-1024x799.jpg 1024w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-2-300x234.jpg 300w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-2-768x600.jpg 768w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-2-1536x1199.jpg 1536w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-2-370x289.jpg 370w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-2-840x656.jpg 840w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-2-410x320.jpg 410w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-2-600x468.jpg 600w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-2.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"33041\" src=\"https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-3-1024x576.jpg\" alt=\"\" class=\"wp-image-33041\" srcset=\"https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-3-1024x576.jpg 1024w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-3-300x169.jpg 300w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-3-768x432.jpg 768w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-3-1536x864.jpg 1536w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-3-370x208.jpg 370w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-3-1290x725.jpg 1290w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-3-840x473.jpg 840w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-3-410x231.jpg 410w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-3-600x338.jpg 600w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-3-270x152.jpg 270w, https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-content\/uploads\/2023\/05\/post-3.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Lorem ipsum dolor sit amet, consetetur sadipscing elitr, sed diam nonumy eirmod tempor invidunt labore dolore magna erat, sed diam voluptua. At vero eos et accusam et justo duo dolores et  rebum. Stet clita bergren, no sea takimata sanctus.<\/p>\n","protected":false},"author":1,"featured_media":33485,"comment_status":"closed","ping_status":"closed","template":"","cpt_portfolio_group":[263],"class_list":["post-2987","cpt_portfolio","type-cpt_portfolio","status-publish","has-post-thumbnail","hentry","cpt_portfolio_group-transfer"],"_links":{"self":[{"href":"https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-json\/wp\/v2\/cpt_portfolio\/2987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-json\/wp\/v2\/cpt_portfolio"}],"about":[{"href":"https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-json\/wp\/v2\/types\/cpt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-json\/wp\/v2\/comments?post=2987"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-json\/wp\/v2\/media\/33485"}],"wp:attachment":[{"href":"https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-json\/wp\/v2\/media?parent=2987"}],"wp:term":[{"taxonomy":"cpt_portfolio_group","embeddable":true,"href":"https:\/\/thecarltonhotelfolkestone.com\/2026\/wp-json\/wp\/v2\/cpt_portfolio_group?post=2987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}